{"id":5771,"date":"2020-11-11T21:42:25","date_gmt":"2020-11-11T20:42:25","guid":{"rendered":"https:\/\/radiosummernight.ch\/upload\/2020\/11\/beckenbauer-angeschnitten441.mp3"},"modified":"2020-11-11T21:42:27","modified_gmt":"2020-11-11T20:42:27","slug":"beckenbauer-angeschnitten441","status":"inherit","type":"attachment","link":"https:\/\/radiosummernight.ch\/fr\/?attachment_id=5771","title":{"rendered":"beckenbauer-angeschnitten441"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":""},"class_list":["post-5771","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-5771-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/radiosummernight.ch\/upload\/2020\/11\/beckenbauer-angeschnitten441.mp3?_=1\" \/><a href=\"https:\/\/radiosummernight.ch\/upload\/2020\/11\/beckenbauer-angeschnitten441.mp3\">https:\/\/radiosummernight.ch\/upload\/2020\/11\/beckenbauer-angeschnitten441.mp3<\/a><\/audio>\n<p>&#8220;beckenbauer-angeschnitten441&#8221;.<\/p>\n"},"caption":{"rendered":"<p>https:\/\/radiosummernight.ch\/upload\/2020\/11\/beckenbauer-angeschnitten441.mp3 &#8220;beckenbauer-angeschnitten441&#8221;.<\/p>\n"},"alt_text":"","media_type":"file","mime_type":"audio\/mpeg","media_details":{"dataformat":"mp3","channels":"2","sample_rate":"44100","bitrate":"128000","channelmode":"stereo","bitrate_mode":"cbr","lossless":"0","encoder_options":"CBR128","compression_ratio":"0.0907029478458","fileformat":"mp3","filesize":"150344","mime_type":"audio\/mpeg","length":"9","length_formatted":"0:09","artist":"","album":"","sizes":{}},"post":5768,"source_url":"https:\/\/radiosummernight.ch\/upload\/2020\/11\/beckenbauer-angeschnitten441.mp3","_links":{"self":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/media\/5771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/comments?post=5771"}]}}