{"id":10318,"date":"2022-11-23T12:01:56","date_gmt":"2022-11-23T11:01:56","guid":{"rendered":"https:\/\/radiosummernight.ch\/?p=10318"},"modified":"2022-11-23T12:01:56","modified_gmt":"2022-11-23T11:01:56","slug":"la-gustav-2023-jetzt-anmelden-nur-noch-bis-zum-25-11-moeglich","status":"publish","type":"post","link":"https:\/\/radiosummernight.ch\/fr\/la-gustav-2023-jetzt-anmelden-nur-noch-bis-zum-25-11-moeglich\/","title":{"rendered":"LA GUSTAV 2023 &#8211; Jetzt anmelden nur noch bis zum 25.11 m\u00f6glich!"},"content":{"rendered":"<p>Ist f\u00fcr dich das Kreieren und Auff\u00fchren eigener Songs mehr als nur ein Hobby?<\/p>\n<p>Sp\u00fcrst du einen inneren Drang, eigene Musik erschaffen zu wollen?<\/p>\n<p>Macht es dich gl\u00fccklich, wenn du deine Musik vor Publikum auff\u00fchren kannst &#8211; alleine oder mit Band?<\/p>\n<p>Wenn ja, dann melde dich bei LA GUSTAV an.<\/p>\n<p>&nbsp;<\/p>\n<p>Ein einj\u00e4hriges Musikstipendium f\u00fcr junge Talente der aktuellen Musik im Wert von \u00fcber 10\u2018000 CHF.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>Teilnahmebedingungen<\/u><\/strong><\/p>\n<ul>\n<li>18 &#8211; 25 j\u00e4hrig<\/li>\n<li>Singer\/Songwriter*innen, Producer*innen, Rapper*innen, Beatmaker*innen, Instrumentalist*innen<\/li>\n<li>Neu k\u00f6nnen sich auch Bands anmelden<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><u>Was dich erwarten wird <\/u><\/strong><\/p>\n<ul>\n<li>7 Music-Weekends in diversen Schweizer Musikklubs<\/li>\n<li>1 Woche Songwriting Camp<\/li>\n<li>Diverse Kurse und Masterclasses<\/li>\n<li>Showcases an grossen und kleinen Sommerfestivals<\/li>\n<li>Vernetzung mit der professionellen Schweizer Musikszene<\/li>\n<li>Starterkit f\u00fcr deine Karriere: Song, Video, Pressefoto, Pressetext, Liveaufnahme<\/li>\n<li>Live-Auftritt in London<\/li>\n<li>Final Show Fri-Son &amp; Final Tour div. Clubs<\/li>\n<li>Vernetzung mit jungen Musiker:innen aus der ganzen Schweiz<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><u>Auditions<\/u><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Um an einer Audition teilnehmen zu k\u00f6nnen, musst du uns zuerst ein Selfie-Video schicken, auf dem du uns dein K\u00f6nnen zeigst. Anmeldung und Infos findest du auf unserer Webseite.<\/p>\n<p>Einsendeschluss ist der 25.11.22<\/p>\n<p>&nbsp;<\/p>\n<p>01.12.2022 Les Docks <sup>VD <\/sup><\/p>\n<p>02.12.2022 Sommercasino <sup>BS<\/sup><\/p>\n<p>06.12.2022 Fri-Son <sup>FR<\/sup><\/p>\n<p>09.12.2022 Sch\u00fc\u00fcr <sup>LU<\/sup><\/p>\n<p>10.12.2022 Dynamo <sup>ZH<\/sup><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/lagustav.ch\" target=\"_blank\" rel=\"noopener\">https:\/\/lagustav.ch<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Ist f\u00fcr dich das Kreieren und Auff\u00fchren eigener Songs mehr als nur ein Hobby? Sp\u00fcrst du einen inneren Drang, eigene Musik erschaffen zu wollen? Macht es dich gl\u00fccklich, wenn du deine Musik vor Publikum auff\u00fchren kannst &#8211; alleine oder mit Band? Wenn ja, dann melde dich bei LA GUSTAV an. &nbsp; Ein einj\u00e4hriges Musikstipendium f\u00fcr&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/radiosummernight.ch\/fr\/la-gustav-2023-jetzt-anmelden-nur-noch-bis-zum-25-11-moeglich\/\">Read more<\/a><\/p>","protected":false},"author":60,"featured_media":10323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[5],"tags":[317,319,316,11,318],"series":[],"class_list":["post-10318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events","tag-anmeldung","tag-auditions","tag-la-gustave","tag-musik","tag-musikstipendium"],"episode_featured_image":"https:\/\/radiosummernight.ch\/upload\/2022\/11\/La-Gustav-23-FB-scaled.jpg","episode_player_image":"https:\/\/radiosummernight.ch\/upload\/2021\/03\/Logo-RSN-Schwarz-300x300-Green.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"light","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/us\/podcast\/radio-summernight\/id1647787397?uo=4&itsct=podtail_podcasts&itscg=30200&ls=1&at=1001l39ag&ct=deutschepodcasts.de","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"deezer":{"key":"deezer","url":"https:\/\/deezer.page.link\/NKiaDgyHm5ekBXsE7","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"https:\/\/podcasts.google.com\/feed\/aHR0cHM6Ly9yYWRpb3N1bW1lcm5pZ2h0LmNoL2ZlZWQvcG9kY2FzdA?sa=X&ved=0CAMQ4aUDahcKEwj4gc2i0oP8AhUAAAAAHQAAAAAQAQ&hl=de-CH","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"podcast_de":{"key":"podcast_de","url":"https:\/\/www.podcast.de\/podcast\/3070299\/radio-summernight","label":"Podcast.de","class":"podcast_de","icon":"podcast-de.png"},"spotify":{"key":"spotify","url":"https:\/\/open.spotify.com\/show\/4DnvrNRnOIGTWoVH4yoIpC","label":"Spotify","class":"spotify","icon":"spotify.png"},"itunes":{"key":"itunes","url":"","label":"iTunes","class":"itunes","icon":"itunes.png"},"mytuner_radio":{"key":"mytuner_radio","url":"","label":"myTuner Radio","class":"mytuner_radio","icon":"mytuner-radio.png"}},"rssFeedUrl":"https:\/\/radiosummernight.ch\/fr\/feed\/podcast\/radio-summernight","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"oUDIB4SUtq\"><a href=\"https:\/\/radiosummernight.ch\/fr\/la-gustav-2023-jetzt-anmelden-nur-noch-bis-zum-25-11-moeglich\/\">LA GUSTAV 2023 &#8211; Jetzt anmelden nur noch bis zum 25.11 m\u00f6glich!<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/radiosummernight.ch\/fr\/la-gustav-2023-jetzt-anmelden-nur-noch-bis-zum-25-11-moeglich\/embed\/#?secret=oUDIB4SUtq\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0LA GUSTAV 2023 &#8211; Jetzt anmelden nur noch bis zum 25.11 m\u00f6glich!\u00a0\u00bb &#8212; Radio Summernight\" data-secret=\"oUDIB4SUtq\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/radiosummernight.ch\/includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/posts\/10318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/comments?post=10318"}],"version-history":[{"count":0,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/posts\/10318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/media\/10323"}],"wp:attachment":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/media?parent=10318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/categories?post=10318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/tags?post=10318"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/series?post=10318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}