{"id":18991,"date":"2024-06-03T15:32:53","date_gmt":"2024-06-03T13:32:53","guid":{"rendered":"https:\/\/radiosummernight.ch\/?p=18991"},"modified":"2024-06-03T17:03:34","modified_gmt":"2024-06-03T15:03:34","slug":"schule-rotweg-projektwoche-schulhaus-rotweg","status":"publish","type":"post","link":"https:\/\/radiosummernight.ch\/fr\/schule-rotweg-projektwoche-schulhaus-rotweg\/","title":{"rendered":"Schule Rotweg: Projektwoche &#8220;Sprache und Bewegung&#8221;"},"content":{"rendered":"<p style=\"text-align: left;\">Was h\u00e4ltst du von den Angeboten dieser Projektwoche? Was gef\u00e4llt dir am besten? Wir haben Sch\u00fclerinnen und Sch\u00fcler zu diesem Thema befragt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Was h\u00e4ltst du von den Angeboten dieser Projektwoche? Was gef\u00e4llt dir am besten? Wir haben Sch\u00fclerinnen und Sch\u00fcler zu diesem Thema befragt.<\/p>","protected":false},"author":51,"featured_media":19015,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"episode_type":"audio","audio_file":"https:\/\/radiosummernight.ch\/upload\/Radiobeitrag_Jonathan-ud-Lovis.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"4:54","filesize":"2.52M","filesize_raw":"2641140","date_recorded":"2024-06-03 15:32:53","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[719],"tags":[],"series":[1573],"class_list":["post-18991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-kurse","series-radio-summernight"],"episode_featured_image":"https:\/\/radiosummernight.ch\/upload\/feedback-3239454_1280.jpg","episode_player_image":"https:\/\/radiosummernight.ch\/upload\/2021\/03\/Logo-RSN-Schwarz-300x300-Green.png","download_link":"https:\/\/radiosummernight.ch\/podcast-download\/18991\/schule-rotweg-projektwoche-schulhaus-rotweg.mp3","player_link":"https:\/\/radiosummernight.ch\/podcast-player\/18991\/schule-rotweg-projektwoche-schulhaus-rotweg.mp3","audio_player":"<audio class=\"wp-audio-shortcode\" id=\"audio-18991-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/radiosummernight.ch\/podcast-player\/18991\/schule-rotweg-projektwoche-schulhaus-rotweg.mp3?_=1\" \/><a href=\"https:\/\/radiosummernight.ch\/podcast-player\/18991\/schule-rotweg-projektwoche-schulhaus-rotweg.mp3\">https:\/\/radiosummernight.ch\/podcast-player\/18991\/schule-rotweg-projektwoche-schulhaus-rotweg.mp3<\/a><\/audio>","episode_data":{"playerMode":"light","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/us\/podcast\/radio-summernight\/id1647787397?%20uo=4&itsct=podtail_podcasts&itscg=30200&ls=1&at=1001l39ag&ct=deutschepodcasts.de","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"deezer":{"key":"deezer","url":"https:\/\/deezer.page.link\/NKiaDgyHm5ekBXsE7","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"https:\/\/podcasts.google.com\/feed\/aHR0cHM6Ly9yYWRpb3N1bW1lcm5pZ2h0LmNoL2ZlZWQvcG9kY2FzdA?%20sa=X&ved=0CAMQ4aUDahcKEwj4gc2i0oP8AhUAAAAAHQAAAAAQAQ&hl=de-CH","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"podcast_de":{"key":"podcast_de","url":"https:\/\/www.podcast.de\/podcast\/3070299\/radio-summernight","label":"Podcast.de","class":"podcast_de","icon":"podcast-de.png"},"spotify":{"key":"spotify","url":"https:\/\/open.spotify.com\/show\/4DnvrNRnOIGTWoVH4yoIpC","label":"Spotify","class":"spotify","icon":"spotify.png"},"itunes":{"key":"itunes","url":"","label":"iTunes","class":"itunes","icon":"itunes.png"},"mytuner_radio":{"key":"mytuner_radio","url":"","label":"myTuner Radio","class":"mytuner_radio","icon":"mytuner-radio.png"}},"rssFeedUrl":"https:\/\/radiosummernight.ch\/fr\/feed\/podcast\/radio-summernight","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"nN8NNRn1ok\"><a href=\"https:\/\/radiosummernight.ch\/fr\/schule-rotweg-projektwoche-schulhaus-rotweg\/\">Schule Rotweg: Projektwoche &#8220;Sprache und Bewegung&#8221;<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/radiosummernight.ch\/fr\/schule-rotweg-projektwoche-schulhaus-rotweg\/embed\/#?secret=nN8NNRn1ok\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0Schule Rotweg: Projektwoche &#8220;Sprache und Bewegung&#8221;\u00a0\u00bb &#8212; Radio Summernight\" data-secret=\"nN8NNRn1ok\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/radiosummernight.ch\/includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/posts\/18991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/comments?post=18991"}],"version-history":[{"count":0,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/posts\/18991\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/media\/19015"}],"wp:attachment":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/media?parent=18991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/categories?post=18991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/tags?post=18991"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/series?post=18991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}