{"id":7022,"date":"2021-06-15T21:48:14","date_gmt":"2021-06-15T19:48:14","guid":{"rendered":"https:\/\/radiosummernight.ch\/?p=7022"},"modified":"2025-10-26T15:40:25","modified_gmt":"2025-10-26T14:40:25","slug":"pink-floyd-roger-waters-beleidigt-mark-zuckerberg","status":"publish","type":"post","link":"https:\/\/radiosummernight.ch\/fr\/pink-floyd-roger-waters-beleidigt-mark-zuckerberg\/","title":{"rendered":"PINK FLOYD: Roger Waters beleidigt Mark Zuckerberg"},"content":{"rendered":"<p class=\"lead\">&#8220;Another Brick In The Wall, Part 2&#8221; f\u00fcr Insta? Never! Auch mit David Gilmour streitet Waters weiter.<\/p>\n<p>New York (<strong><a class=\"vor\" href=\"mailto:ebi@laut.de\">ebi<\/a><\/strong>) &#8211;\u00a0Dass es\u00a0<a class=\"vor\" title=\"ESC in Israel: Waters, Eno u.a. rufen zum Boykott auf\" href=\"https:\/\/www.laut.de\/news\/15082\" target=\"_blank\" rel=\"noopener\">BDS-Supporter<\/a>\u00a0<a class=\"wort\" title=\"Roger Waters\" href=\"https:\/\/www.laut.de\/artist\/1823\" target=\"_blank\" rel=\"noopener\">Roger Waters<\/a>\u00a0mit der so genannten feinen Englischen nicht unbedingt hat, ist nicht neu. J\u00fcngstes Beispiel: Facebook-Chef Mark Zuckerberg bezeichnete er u.a. als &#8220;<i>einen der m\u00e4chtigsten Idioten der Welt<\/i>&#8220;. Anlass der Beleidigung war eine Anfrage des Internet-Konzerns, den\u00a0<a class=\"wort\" title=\"Pink Floyd\" href=\"https:\/\/www.laut.de\/artist\/544\" target=\"_blank\" rel=\"noopener\">Pink Floyd<\/a>-Hit &#8220;<a class=\"stark\" title=\"Pink Floyd - &#039;The Wall&#039;\" href=\"https:\/\/www.laut.de\/release\/67569\" target=\"_blank\" rel=\"noopener\">Another Brick In The Wall, Part 2<\/a>&#8221; f\u00fcr ein Instagram-Ad nutzen zu d\u00fcrfen.<\/p>\n<div id=\"aslot--de-desktop-04\" class=\"aslot aslot--intext\" data-google-query-id=\"CKK_za6zmvECFUVN4AodBYMP5A\">\n<div id=\"google_ads_iframe_\/33532245\/de-desktop-04_0__container__\"><\/div>\n<\/div>\n<p>&#8220;<i>Fuck you. No fucking way<\/i>&#8220;, lautete Waters klare Antwort. Zumindest sagte er dies in New York in einer Rede auf einem Event zur Unterst\u00fctzung des in London inhaftierten Wikileaks-Gr\u00fcnders Julian Assange, in der er aus einer angeblichen Mail von Zuckerberg zitierte. Der habe im Gegenzug eine riesige Menge Geld geboten: &#8220;<i>Ich erw\u00e4hne das nur, weil es Zeichen ihrer heimt\u00fcckischen Bewegung ist, um absolut alles zu \u00fcbernehmen. Sie wollen ihn verwenden, um Facebook und Instagram noch gr\u00f6\u00dfer und m\u00e4chtiger zu machen, als sie ohnehin schon sind, um uns alle in diesem Raum weiterhin zensieren zu k\u00f6nnen und zu verhindern, dass Julian Assanges Geschichte an die \u00d6ffentlichkeit gelangt<\/i>&#8220;, redete sich der Musiker in Rage.<\/p>\n<p>Und weiter: &#8220;<i>An diejenigen von uns, die Macht besitzen, und ich habe ein kleines bisschen, bez\u00fcglich der Ver\u00f6ffentlichung meiner Songs sowieso, also ich mache bei diesem Bullshit nicht mit<\/i>&#8220;.<\/p>\n<p><b>Streit um &#8220;Animals&#8221;<\/b><\/p>\n<p>Erst k\u00fcrzlich hatte sich Waters auch wieder mit Pink Floyd-Kollege\u00a0<a class=\"wort\" title=\"David Gilmour\" href=\"https:\/\/www.laut.de\/artist\/4974\" target=\"_blank\" rel=\"noopener\">David Gilmour<\/a>\u00a0angelegt: Letzterer hatte sein Veto gegen die von Waters in Auftrag gegebenen Liner Notes zum Re-Release von &#8220;Animals&#8221; (1977) eingelegt. Waters stellte diese daraufhin online und behauptete, Gilmour habe dies nur aus dem Grund verhindert, weil er, Waters, in den k\u00fcnstlerischen Mittelpunkt des &#8220;Animals&#8221;-Projekts ger\u00fcckt werde. Waters k\u00fcndigte im Zuge des Streits au\u00dferdem seine Memoiren an. Dort werde er noch mehr Beispiele schildern, wie Gilmour versucht habe, mehr Anerkennung f\u00fcr das Werk Pink Floyds zu beanspruchen, als ihm eigentlich zustehe.<\/p>\n<p>Gilmour wiederum verlautete, &#8220;Animals&#8221; habe niemals Liner Notes besessen. Dass sie nun ein Journalist geschrieben habe, akzeptiere er nicht, und an die Adresse Waters: &#8220;<i>Das hat ihn ein bisschen aufgebracht. Sie wissen ja wie er ist, der Arme<\/i>&#8220;. Au\u00dferdem habe er keine Lust, auf jede Unwahrheit zu reagieren, die \u00fcber ihn verbreitet werde, denn am Ende k\u00e4men die Dinge eh immer so, wie sie sein sollten.<\/p>\n<p>Ob und wann der neue &#8220;Animals&#8221;-Mix, den beide offenbar f\u00fcr gut befinden, erscheinen wird, steht weiter in den Sternen. Gilmour jedenfalls bezeichnete eine Einigung mit Waters derzeit f\u00fcr ziemlich unwahrscheinlich.<\/p>\n<p>&nbsp;<\/p>\n<p>Mehr davon auf <a href=\"https:\/\/laut.de\" target=\"_blank\" rel=\"noopener\">laut.de<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8220;Another Brick In The Wall, Part 2&#8221; f\u00fcr Insta? Never! Auch mit David Gilmour streitet Waters weiter. New York (ebi) &#8211;\u00a0Dass es\u00a0BDS-Supporter\u00a0Roger Waters\u00a0mit der so genannten feinen Englischen nicht unbedingt hat, ist nicht neu. J\u00fcngstes Beispiel: Facebook-Chef Mark Zuckerberg bezeichnete er u.a. als &#8220;einen der m\u00e4chtigsten Idioten der Welt&#8220;. Anlass der Beleidigung war eine Anfrage&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/radiosummernight.ch\/fr\/pink-floyd-roger-waters-beleidigt-mark-zuckerberg\/\">Read more<\/a><\/p>","protected":false},"author":1,"featured_media":7024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[719],"tags":[33],"series":[],"class_list":["post-7022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-kurse","tag-content-partnerschaft-mit-laut-de"],"episode_featured_image":"https:\/\/radiosummernight.ch\/upload\/2021\/06\/roger-waters-koeln-lanxess-arena-192063.jpg","episode_player_image":"https:\/\/radiosummernight.ch\/upload\/2021\/03\/Logo-RSN-Schwarz-300x300-Green.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"light","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/us\/podcast\/radio-summernight\/id1647787397?uo=4&itsct=podtail_podcasts&itscg=30200&ls=1&at=1001l39ag&ct=deutschepodcasts.de","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"deezer":{"key":"deezer","url":"https:\/\/deezer.page.link\/NKiaDgyHm5ekBXsE7","label":"Deezer","class":"deezer","icon":"deezer.png"},"google_podcasts":{"key":"google_podcasts","url":"https:\/\/podcasts.google.com\/feed\/aHR0cHM6Ly9yYWRpb3N1bW1lcm5pZ2h0LmNoL2ZlZWQvcG9kY2FzdA?sa=X&ved=0CAMQ4aUDahcKEwj4gc2i0oP8AhUAAAAAHQAAAAAQAQ&hl=de-CH","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"podcast_de":{"key":"podcast_de","url":"https:\/\/www.podcast.de\/podcast\/3070299\/radio-summernight","label":"Podcast.de","class":"podcast_de","icon":"podcast-de.png"},"spotify":{"key":"spotify","url":"https:\/\/open.spotify.com\/show\/4DnvrNRnOIGTWoVH4yoIpC","label":"Spotify","class":"spotify","icon":"spotify.png"},"itunes":{"key":"itunes","url":"","label":"iTunes","class":"itunes","icon":"itunes.png"},"mytuner_radio":{"key":"mytuner_radio","url":"","label":"myTuner Radio","class":"mytuner_radio","icon":"mytuner-radio.png"}},"rssFeedUrl":"https:\/\/radiosummernight.ch\/fr\/feed\/podcast\/radio-summernight","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"9Rwy7qKT2p\"><a href=\"https:\/\/radiosummernight.ch\/fr\/pink-floyd-roger-waters-beleidigt-mark-zuckerberg\/\">PINK FLOYD: Roger Waters beleidigt Mark Zuckerberg<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/radiosummernight.ch\/fr\/pink-floyd-roger-waters-beleidigt-mark-zuckerberg\/embed\/#?secret=9Rwy7qKT2p\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0PINK FLOYD: Roger Waters beleidigt Mark Zuckerberg\u00a0\u00bb &#8212; Radio Summernight\" data-secret=\"9Rwy7qKT2p\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/radiosummernight.ch\/includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/posts\/7022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/comments?post=7022"}],"version-history":[{"count":0,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/posts\/7022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/media\/7024"}],"wp:attachment":[{"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/media?parent=7022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/categories?post=7022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/tags?post=7022"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/radiosummernight.ch\/fr\/wp-json\/wp\/v2\/series?post=7022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}